{"id":8390,"date":"2021-05-26T00:17:03","date_gmt":"2021-05-26T00:17:03","guid":{"rendered":"https:\/\/directresearchpublisher.org\/drjphet\/?p=8390"},"modified":"2021-06-14T13:16:47","modified_gmt":"2021-06-14T13:16:47","slug":"vol-6-may-2021","status":"publish","type":"post","link":"https:\/\/directresearchpublisher.org\/drjphet\/vol-6-may-2021\/","title":{"rendered":"Vol. 6, May 2021"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"views":118,"_links":{"self":[{"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/posts\/8390"}],"collection":[{"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/comments?post=8390"}],"version-history":[{"count":8,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/posts\/8390\/revisions"}],"predecessor-version":[{"id":8410,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/posts\/8390\/revisions\/8410"}],"wp:attachment":[{"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/media?parent=8390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/categories?post=8390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/directresearchpublisher.org\/drjphet\/wp-json\/wp\/v2\/tags?post=8390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}